{"id":4966,"date":"2026-07-15T10:32:22","date_gmt":"2026-07-15T08:32:22","guid":{"rendered":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/?post_type=tribe_events&#038;p=4966"},"modified":"2026-07-15T10:33:57","modified_gmt":"2026-07-15T08:33:57","slug":"uebungsabend-unserer-singgruppe-20-07-26-uhr-ab-19-00-uhr-im-klostergarten","status":"publish","type":"tribe_events","link":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/termin\/uebungsabend-unserer-singgruppe-20-07-26-uhr-ab-19-00-uhr-im-klostergarten\/","title":{"rendered":"\u00dcbungsabend unserer Singgruppe 20.07.26 Uhr ab 19.00 Uhr im Klostergarten"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\tJuli 20\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--date\">\n\t\t\t\t @ \t\t\t<\/span>\n\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--start\">\n\t\t\t\t19:00\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__separator tribe-events-schedule__separator--time\">\n\t\t\t\t\t &#8211; \t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"tribe-events-schedule__time tribe-events-schedule__time--end\">\n\t\t\t\t\t21:00\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-content\/uploads\/2026\/07\/2026-07-20-Singgruppe-HVB.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1358\" src=\"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-content\/uploads\/2026\/07\/2026-07-20-Singgruppe-HVB-960x1358.jpeg\" alt=\"\" class=\"wp-image-4967\" srcset=\"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-content\/uploads\/2026\/07\/2026-07-20-Singgruppe-HVB-960x1358.jpeg 960w, https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-content\/uploads\/2026\/07\/2026-07-20-Singgruppe-HVB-620x877.jpeg 620w, https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-content\/uploads\/2026\/07\/2026-07-20-Singgruppe-HVB-768x1086.jpeg 768w, https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-content\/uploads\/2026\/07\/2026-07-20-Singgruppe-HVB-1086x1536.jpeg 1086w, https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-content\/uploads\/2026\/07\/2026-07-20-Singgruppe-HVB.jpeg 1414w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/figure>\n\n\n<div  class=\"tribe-block tribe-block__event-price\" >\n\t\t<\/div>\n\n\n<div  class=\"tribe-block tribe-block__organizer__details tribe-clearfix\" >\n\t<div class=\"tribe-block__organizer__title\">\n\t\t<h3>Singgruppe des Heimatverein Bersenbr\u00fcck<\/h3>\n\t<\/div>\n\t\t\t<\/div>\n\n\n<div  class=\"tribe-block tribe-block__venue tribe-clearfix\" >\n\t\n\t\t\n\t<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"Zeige Links an um Veranstaltungen zu deinem Kalender hinzuzuf\u00fcgen\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tZum Kalender hinzuf\u00fcgen\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20260720T190000\/20260720T210000&#038;text=%C3%9Cbungsabend%20unserer%20Singgruppe%2020.07.26%20Uhr%20ab%2019.00%20Uhr%20im%20Klostergarten&#038;details=%3Cfigure+class%3D%22wp-block-image+size-large%22%3E%3Ca+href%3D%22https%3A%2F%2Fheimatvereinbersenbrueck.de%2Fwordpress%2Fwp-content%2Fuploads%2F2026%2F07%2F2026-07-20-Singgruppe-HVB.jpeg%22%3E%3Cimg+src%3D%22https%3A%2F%2Fheimatvereinbersenbrueck.de%2Fwordpress%2Fwp-content%2Fuploads%2F2026%2F07%2F2026-07-20-Singgruppe-HVB-960x1358.jpeg%22+alt%3D%22%22+class%3D%22wp-image-4967%22%2F%3E%3C%2Fa%3E%3C%2Ffigure%3E&#038;trp=false&#038;ctz=Europe\/Berlin&#038;sprop=website:https:\/\/heimatvereinbersenbrueck.de\/wordpress\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tGoogle Kalender\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":4967,"template":"","meta":{"pgc_sgb_lightbox_settings":"","_EventAllDay":false,"_EventTimezone":"Europe\/Berlin","_EventStartDate":"2026-07-20 19:00:00","_EventEndDate":"2026-07-20 21:00:00","_EventStartDateUTC":"2026-07-20 17:00:00","_EventEndDateUTC":"2026-07-20 19:00:00","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"EUR","_EventCurrencyPosition":"suffix","_EventDateTimeSeparator":" @ ","_EventTimeRangeSeparator":" - ","_EventOrganizerID":[4235],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[75],"class_list":["post-4966","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-singgruppe-hvb","cat_singgruppe-hvb"],"_links":{"self":[{"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/4966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/4966\/revisions"}],"predecessor-version":[{"id":4968,"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/4966\/revisions\/4968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/media\/4967"}],"wp:attachment":[{"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/media?parent=4966"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/tags?post=4966"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/heimatvereinbersenbrueck.de\/wordpress\/wp-json\/wp\/v2\/tribe_events_cat?post=4966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}